{"id":9060457,"date":"2026-02-13T09:30:24","date_gmt":"2026-02-13T08:30:24","guid":{"rendered":"https:\/\/www.fitness-flohmarkt.ch\/produkt\/keiser-indoor-cycle-m3-spinning-bike\/"},"modified":"2026-04-20T16:50:36","modified_gmt":"2026-04-20T14:50:36","slug":"keiser-indoor-cycle-m3-spinning-bike","status":"publish","type":"product","link":"https:\/\/www.fitness-flohmarkt.ch\/it\/produkt\/keiser-indoor-cycle-m3-spinning-bike\/","title":{"rendered":"Keiser Indoor Cycle M3 | Spinning Bike"},"content":{"rendered":"<h3 data-start=\"382\" data-end=\"454\">Keiser M3 - La classica indoor bike con qualit\u00e0 da studio purista<\/h3>\n<p data-start=\"456\" data-end=\"801\">La Keiser M3 (5501BBN) \u00e8 la versione base della leggendaria serie di indoor cycle Keiser ed \u00e8 sinonimo di massima robustezza e durata senza compromessi. Sviluppata per l'uso professionale in studio, la cyclette convince per il suo sistema di freni magnetici a bassa manutenzione, la silenziosa trasmissione a cinghia e la stabile struttura del telaio a V.<\/p>\n<p data-start=\"803\" data-end=\"979\">A differenza dell'M3i, l'M3 rinuncia volutamente a un display e si concentra interamente su un'esperienza di allenamento classica e affidabile.<\/p>\n<h4 data-start=\"1799\" data-end=\"1853\">La collaudata tecnologia Keiser garantisce la massima affidabilit\u00e0<\/h4>\n<p data-start=\"1855\" data-end=\"2158\">La trasmissione a cinghia trapezoidale Poly-V, esente da manutenzione, in combinazione con il sistema di resistenza magnetica, garantisce una corsa praticamente silenziosa e fluida. Con 24 livelli di resistenza, l'allenamento pu\u00f2 essere controllato con precisione: da semplici corse di resistenza a intervalli intensivi.<\/p>\n<p data-start=\"2160\" data-end=\"2246\">La funzione di arresto rapido integrata offre un'ulteriore sicurezza per ogni unit\u00e0.<\/p>\n<h4 data-start=\"2253\" data-end=\"2292\">Ergonomia e comfort senza compromessi<\/h4>\n<p data-start=\"2294\" data-end=\"2423\">La stabile struttura a V garantisce la massima stabilit\u00e0 e un'elevata capacit\u00e0 di carico nell'uso quotidiano in studio.<\/p>\n<p data-start=\"2425\" data-end=\"2605\">Il manubrio pu\u00f2 essere regolato verticalmente (a 2 vie) e la sella sia orizzontalmente che verticalmente (a 4 vie), consentendo alla bici di adattarsi in modo ottimale alle diverse corporature.<\/p>\n<p data-start=\"2607\" data-end=\"2775\">I pedali combinati (sistema a scatto SPD + tazze), il sellino comfort, le imbottiture elastiche, il portaborraccia integrato e le ruote per il trasporto offrono un comfort aggiuntivo.<\/p>\n<h4 data-start=\"2782\" data-end=\"2817\">Dati tecnici in sintesi<\/h4>\n<ul>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"2819\" data-end=\"2841\">Sistema di resistenza:<\/strong> Freno magnetico con 24 marce<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"2883\" data-end=\"2895\">Guida:<\/strong> Cinghia trapezoidale Poly-V esente da manutenzione<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"3094\" data-end=\"3112\">Connettivit\u00e0:<\/strong> nessuno<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"3121\" data-end=\"3143\">Regolazione del manubrio:<\/strong> verticale (2 vie)<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"3163\" data-end=\"3185\">Regolazione della sella:<\/strong> orizzontale + verticale (4 vie)<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"3218\" data-end=\"3229\">Telaio:<\/strong> Struttura a V<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"3253\" data-end=\"3264\">Pedali:<\/strong> Pedali combi (SPD click \/ gabbia da corsa)<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"3306\" data-end=\"3329\">Peso massimo. peso dell'utente:<\/strong> 136 kg<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"3339\" data-end=\"3350\">Extra:<\/strong> Funzione di arresto rapido, portabottiglie, rotelle di trasporto<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong data-start=\"3470\" data-end=\"3480\">Colore:<\/strong> Nero con accenti rossi<\/li>\n<li><strong data-start=\"3627\" data-end=\"3639\">Peso:<\/strong> 39 kg<\/li>\n<li data-start=\"2819\" data-end=\"3509\"><strong>Keiser SKU:<\/strong> 5501BBN<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La indoor bike Keiser M3 senza display \u00e8 una bike collaudata per uso professionale. Trasmissione a cinghia che non richiede manutenzione, sistema di resistenza magnetica a 24 livelli, praticamente silenzioso. Manubrio regolabile in 2 direzioni, sella regolabile in 4 direzioni. Pedali combinati (SPD\/gabbia), peso massimo dell'utente 136 kg. Robusta e durevole.<\/p>","protected":false},"featured_media":9065177,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_gspb_post_css":""},"product_brand":[1041],"product_cat":[818,304,311],"product_tag":[],"class_list":{"0":"post-9060457","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-keiser","7":"product_cat-conditioning","8":"product_cat-reha-physio","9":"product_cat-spinningbikes","10":"product_shipping_class-standard","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":2,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"df_price":1990,"df_sale_price":"","df_regular_price":1990,"df_image_link":"https:\/\/www.fitness-flohmarkt.ch\/wp-content\/uploads\/copy_C4677CF3-9A2B-4F7D-85CA-247DEE6D7B17-3-300x300.avif","_links":{"self":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product\/9060457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/comments?post=9060457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/media\/9065177"}],"wp:attachment":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/media?parent=9060457"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_brand?post=9060457"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_cat?post=9060457"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_tag?post=9060457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}