{"id":9056732,"date":"2026-01-07T09:30:30","date_gmt":"2026-01-07T08:30:30","guid":{"rendered":"https:\/\/www.fitness-flohmarkt.ch\/produkt\/hantelscheiben-wandhalterung-wall-plate-storage\/"},"modified":"2026-07-14T10:31:09","modified_gmt":"2026-07-14T08:31:09","slug":"piastra-di-peso-a-parete-per-il-montaggio-a-parete-della-piastra-di-stoccaggio","status":"publish","type":"product","link":"https:\/\/www.fitness-flohmarkt.ch\/it\/produkt\/hantelscheiben-wandhalterung-wall-plate-storage\/","title":{"rendered":"Supporto a parete per piastre di peso | Custodia per piastre a parete"},"content":{"rendered":"<h3>Supporto a parete per piastre portapesi - Contenitore per piastre a parete<\/h3>\n<p class=\"mb-2 whitespace-pre-wrap\">Il supporto da parete per piastre ponderali \u00e8 adatto per riporre le piastre ponderali in modo organizzato e poco ingombrante direttamente sulla parete. Si monta singolarmente ed \u00e8 ideale per le palestre di casa o gli studi con spazio limitato.<\/p>\n<p class=\"mb-2 whitespace-pre-wrap\">Die schwarze Wandplatte misst 20 x 6 cm und wird mit einem Lochabstand von 15 cm montiert. Der Aufnahmezylinder ist 30 cm lang und bietet damit ausreichend Platz f\u00fcr mehrere Scheiben. Die Halterung ist f\u00fcr alle g\u00e4ngigen Hantelscheiben mit 50 mm Bohrung geeignet.<\/p>\n<p class=\"mb-2 whitespace-pre-wrap\">Durch die Wandbefestigung bleibt der Boden frei, was die \u00dcbersichtlichkeit und Sicherheit im Trainingsbereich verbessert.<\/p>\n<p data-start=\"749\" data-end=\"819\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"749\" data-end=\"761\">Nota:<\/strong> Il materiale di fissaggio non \u00e8 incluso nella fornitura.<\/p>","protected":false},"excerpt":{"rendered":"<p>Supporto a parete per dischi di peso per riporre in modo salvaspazio i dischi di peso con foro da 50 mm. Pu\u00f2 essere montato singolarmente. Mantiene il pavimento libero per una maggiore sicurezza e visione d'insieme.<\/p>","protected":false},"featured_media":9073484,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_gspb_post_css":""},"product_brand":[1000],"product_cat":[319],"product_tag":[],"class_list":["post-9056732","product","type-product","status-publish","has-post-thumbnail","product_brand-fitcom","product_cat-fitness-zubehoer","pa_artikel-pro-verkaufseinheit-1x","pa_breite-6-cm","pa_farbe-chrome-en","pa_hoehe-20-cm","pa_kernmaterial-stahl","pa_lieferumfang-1x-hantelscheibenstaender","pa_lochdurchmesser-50-mm","pa_max-belastung-100-kg","pa_staendertyp-hantelscheibenstaender","pa_tiefe-30-cm","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":129,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"df_price":25,"df_sale_price":"","df_regular_price":25,"df_image_link":"https:\/\/www.fitness-flohmarkt.ch\/wp-content\/uploads\/gewichtstange_2-e1780906318145-6-300x300.avif","_links":{"self":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product\/9056732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/comments?post=9056732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/media\/9073484"}],"wp:attachment":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/media?parent=9056732"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_brand?post=9056732"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_cat?post=9056732"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_tag?post=9056732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}