{"id":6192,"date":"2025-02-09T04:26:49","date_gmt":"2025-02-09T03:26:49","guid":{"rendered":"https:\/\/www2.fitness-flohmarkt.ch\/produkt\/kurzhantel-sets-bis-zu-60-kg-round-dumbbells\/"},"modified":"2026-06-12T17:09:34","modified_gmt":"2026-06-12T15:09:34","slug":"set-di-manubri-fino-a-60-kg-di-manubri-rotondi","status":"publish","type":"product","link":"https:\/\/www.fitness-flohmarkt.ch\/it\/produkt\/kurzhantel-sets-bis-zu-60-kg-round-dumbbells\/","title":{"rendered":"Set di manubri fino a 60 kg | Manubri rotondi"},"content":{"rendered":"<h3 data-start=\"548\" data-end=\"939\"><strong data-start=\"567\" data-end=\"647\">Set di manubri fino a 60 kg - Quattro potenti set per un allenamento intensivo<\/strong><\/h3>\n<p class=\"\" data-start=\"548\" data-end=\"939\">I set di manubri fino a 60 kg offrono quattro opzioni di set adatti a diversi obiettivi di allenamento e livelli di intensit\u00e0. Che si tratti di esercizi di forza pi\u00f9 leggeri o di carichi pesanti, ogni set \u00e8 adatto alle esigenze dei diversi livelli di allenamento.<\/p>\n<p class=\"\" data-start=\"941\" data-end=\"1315\">Questi manubri compatti di alta qualit\u00e0 sono dotati di un'impugnatura ergonomica cromata e di un'anima in fusione gommata, che garantisce la massima durata e protezione del pavimento. L'impugnatura cromata antiscivolo garantisce una presa sicura durante l'allenamento. Questi manubri rotondi sono ideali per l'allenamento funzionale, lo sviluppo della forza e gli esercizi di resistenza.<\/p>\n<p class=\"\" data-start=\"1317\" data-end=\"1495\">I set sono disponibili con incrementi di 2,5 kg e offrono quindi una selezione flessibile dei pesi per un allenamento personalizzato. Sono disponibili le seguenti classi di peso:<\/p>\n<ul data-start=\"1496\" data-end=\"1734\">\n<li class=\"\" data-start=\"1496\" data-end=\"1554\">\n<p class=\"\" data-start=\"1498\" data-end=\"1554\">Da 2,5 a 25 kg (10 paia di manubri), peso totale 275 kg<\/p>\n<\/li>\n<li class=\"\" data-start=\"1555\" data-end=\"1614\">\n<p class=\"\" data-start=\"1557\" data-end=\"1614\">Da 12,5 a 35 kg (10 paia di manubri), peso totale 475 kg<\/p>\n<\/li>\n<li class=\"\" data-start=\"1615\" data-end=\"1674\">\n<p class=\"\" data-start=\"1617\" data-end=\"1674\">Da 27,5 a 50 kg (10 paia di manubri), peso totale 775 kg<\/p>\n<\/li>\n<li class=\"\" data-start=\"1675\" data-end=\"1734\">\n<p class=\"\" data-start=\"1677\" data-end=\"1734\">Da 37,5 a 60 kg (10 paia di manubri), peso totale 975 kg<\/p>\n<\/li>\n<\/ul>\n<p class=\"\" data-start=\"1736\" data-end=\"1831\"><strong>Nota:<\/strong> Il supporto non \u00e8 incluso nel set e pu\u00f2 essere acquistato separatamente. Supporti abbinati: F-64175 - Supporto per manubri 10 volte e F-17471 - Supporto per manubri Premium 10 volte.<\/p>","protected":false},"excerpt":{"rendered":"<p>Set di manubri fino a 60 kg - Quattro diverse opzioni di set: manubri compatti di alta qualit\u00e0 con impugnatura ergonomica cromata e nucleo in fusione gommata per la massima durata e un allenamento intensivo. Ogni set \u00e8 disponibile con incrementi di 2,5 kg per offrire opzioni di allenamento flessibili. I set sono adatti a diverse intensit\u00e0 di allenamento.<\/p>","protected":false},"featured_media":9047232,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_gspb_post_css":""},"product_brand":[1000],"product_cat":[302],"product_tag":[],"class_list":["post-6192","product","type-product","status-publish","has-post-thumbnail","product_brand-fitcom","product_cat-kompakthanteln","pa_anzahl-hanteln-20x","pa_artikel-pro-verkaufseinheit-10x","pa_ergonomischer-griff-ja","pa_farbe-schwarz","pa_hanteltyp-kurzhantel","pa_kernmaterial-gusseisen","pa_lieferumfang-10x-kurzhantel","pa_oberflaeche-gummi","pa_set-12-5-bis-35-kg","pa_set-2-5-bis-25-kg","pa_set-27-5-bis-50-kg","pa_set-37-5-bis-60-kg","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"df_price":890,"df_sale_price":"","df_regular_price":890,"df_image_link":"https:\/\/www.fitness-flohmarkt.ch\/wp-content\/uploads\/Hantelsatz_2.5-25-1_black-scaled-1_1080x1080-300x300.png","_links":{"self":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product\/6192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/comments?post=6192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/media\/9047232"}],"wp:attachment":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/media?parent=6192"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_brand?post=6192"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_cat?post=6192"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_tag?post=6192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}