{"id":1569,"date":"2025-01-14T23:43:07","date_gmt":"2025-01-14T22:43:07","guid":{"rendered":"https:\/\/www2.fitness-flohmarkt.ch\/produkt\/bumper-plates-hitemp\/"},"modified":"2026-07-15T11:13:36","modified_gmt":"2026-07-15T09:13:36","slug":"piastre-paracolpi-hitemp","status":"publish","type":"product","link":"https:\/\/www.fitness-flohmarkt.ch\/it\/produkt\/bumper-plates-hitemp\/","title":{"rendered":"Piastre paracolpi | HiTemp"},"content":{"rendered":"<h3><strong data-start=\"233\" data-end=\"309\">Piastre paracolpi HiTemp - Massima qualit\u00e0 per la massima intensit\u00e0 di allenamento<\/strong><\/h3>\n<p class=\"\" data-start=\"311\" data-end=\"794\">Le piastre paracolpi HiTemp offrono la massima qualit\u00e0 e sono progettate appositamente per l'allenamento intensivo. La superficie completamente gommata racchiude un robusto nucleo in metallo, garantendo cos\u00ec una durata eccezionale. Queste piastre sono ideali per la caduta dei pesi, in quanto assorbono in modo ottimale l'energia d'impatto, proteggono il pavimento e riducono il rumore: perfette per l'uso in studi e palestre domestiche.<\/p>\n<p class=\"\" data-start=\"796\" data-end=\"1111\">La mescola di gomma appositamente sviluppata rende queste piastre paracolpi non solo resistenti, ma anche abbastanza robuste per l'uso all'aperto, in modo da poter sfruttare i loro punti di forza anche in condizioni difficili. Rimangono resistenti e durevoli anche senza tappetini o protezioni aggiuntive. Ancora pi\u00f9 stabili e resistenti delle piastre paracolpi convenzionali: praticamente indistruttibili!<\/p>\n<p class=\"\" data-start=\"1113\" data-end=\"1389\">L'anello interno, realizzato con precisione e con un diametro del foro di 51 mm, garantisce una presa sicura su tutte le barre portamanubri standard da 50 mm. I diversi livelli di peso possono essere identificati rapidamente e facilmente grazie alla codifica a colori.<\/p>\n<p class=\"\" data-start=\"1113\" data-end=\"1389\">Disponibile in pesi da 5 kg a 25 kg.<\/p>","protected":false},"excerpt":{"rendered":"<p>Piastre paracolpi HiTemp: superficie completamente gommata e robusta anima in metallo. Molto resistenti e stabili, anche sotto carichi elevati. Assorbono gli urti e sono delicati sul pavimento. Anello interno in acciaio inox (51 mm) per una presa sicura su manubri da 50 mm. Codice colore per una rapida identificazione del peso. Disponibile da 5 kg a 25 kg.<\/p>","protected":false},"featured_media":59380,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_gspb_post_css":""},"product_brand":[1000],"product_cat":[811,807,331],"product_tag":[],"class_list":["post-1569","product","type-product","status-publish","has-post-thumbnail","product_brand-fitcom","product_cat-bumper-plates","product_cat-50mm-hantelscheiben","product_cat-weightlifting","pa_abwurffaehig-ja","pa_anzahl-gewichte-1x","pa_artikel-pro-verkaufseinheit-1x","pa_dicke-100-mm","pa_dicke-30-mm","pa_dicke-60-mm","pa_dicke-70-mm","pa_dicke-80-mm","pa_durchmesser-45-cm","pa_farbe-blau","pa_farbe-gelb","pa_farbe-gruen","pa_farbe-rot","pa_farbe-weiss","pa_gewicht-10-kg","pa_gewicht-15-kg","pa_gewicht-20-kg","pa_gewicht-25-kg","pa_gewicht-5-kg","pa_kernmaterial-edelstahl","pa_lieferumfang-1x-hantelscheibe","pa_lochdurchmesser-51-mm","pa_materialhaerte-shora-a-70","pa_oberflaeche-gummi","pa_scheibengewichtstyp-bumper-plate","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"df_price":20,"df_sale_price":"","df_regular_price":20,"df_image_link":"https:\/\/www.fitness-flohmarkt.ch\/wp-content\/uploads\/hitemp_all-20250314-111827-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product\/1569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/comments?post=1569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/media\/59380"}],"wp:attachment":[{"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/media?parent=1569"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_brand?post=1569"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_cat?post=1569"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.fitness-flohmarkt.ch\/it\/wp-json\/wp\/v2\/product_tag?post=1569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}